{"id":7716,"date":"2025-06-05T15:33:31","date_gmt":"2025-06-05T21:33:31","guid":{"rendered":"https:\/\/antiguaesportiva.com\/revista\/?p=7716"},"modified":"2025-06-05T15:33:32","modified_gmt":"2025-06-05T21:33:32","slug":"espana-a-la-final-de-la-nations-league-tras-menudo-partido-ante-francia","status":"publish","type":"post","link":"https:\/\/antiguaesportiva.com\/revista\/2025\/06\/05\/espana-a-la-final-de-la-nations-league-tras-menudo-partido-ante-francia\/","title":{"rendered":"\u00a1Espa\u00f1a a la Final de la Nations League, tras menudo partido ante Francia!"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">Espa\u00f1a tumba a Francia y defender\u00e1 t\u00edtulo ante Portugal. &#8216;La Roja&#8217; dominaba por 5-1 en el 67\u2019. Francia pese a sus esfuerzos y encontrar el 5-4, termin\u00f3 sucumbiendo al l\u00edmite. <\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">Espa\u00f1a volvi\u00f3 a demostrar que, a veces, el verdadero arte en el f\u00fatbol es hacer simple lo extraordinario. Sin levantar la voz, con precisi\u00f3n quir\u00fargica y una pasmosa naturalidad, &#8216;La Roja&#8217; escribi\u00f3 un cap\u00edtulo memorable al vencer 5-4 a Francia, un resultado que sacude los libros de historia y la instala en la gran final de la Nations League, donde defender\u00e1 su corona ante Portugal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.formacionsecretarial.edu.gt\/\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"708\" src=\"https:\/\/antiguaesportiva.com\/revista\/wp-content\/uploads\/2025\/05\/nueva-ubica-manta-2@2x.png\" alt=\"\" class=\"wp-image-7483\" style=\"width:304px;height:auto\" srcset=\"https:\/\/antiguaesportiva.com\/revista\/wp-content\/uploads\/2025\/05\/nueva-ubica-manta-2@2x.png 500w, https:\/\/antiguaesportiva.com\/revista\/wp-content\/uploads\/2025\/05\/nueva-ubica-manta-2@2x-212x300.png 212w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">El partido fue un espect\u00e1culo de golpes directos, en el que Espa\u00f1a se plant\u00f3 con inteligencia frente a un rival que sali\u00f3 desmelenado. Didier Deschamps sorprendi\u00f3 a todos con un once ultraofensivo, alineando a Olise, Demb\u00e9l\u00e9, Dou\u00e9 y Mbapp\u00e9, un cuarteto que promet\u00eda v\u00e9rtigo desde el primer minuto. Pero como en el legendario combate entre Muhammad Ali y George Foreman, los de Luis de la Fuente esperaron su momento, resistieron los envites y respondieron con un contragolpe letal.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\">Los primeros veinte minutos fueron una batalla de desgaste. Francia amenazaba y Theo Hern\u00e1ndez estuvo cerca de abrir el marcador, pero Unai Sim\u00f3n, siempre firme bajo los tres palos, desbarat\u00f3 los intentos &#8216;Galos&#8217;. Entonces apareci\u00f3 la pausa y el talento. Oyarzabal, con una clase magistral de control y visi\u00f3n, primero asisti\u00f3 a Nico Williams para el 1-0 al minuto 22 y, tres minutos despu\u00e9s, arm\u00f3 una jugada de fantas\u00eda con Mikel Merino para el 2-0. En apenas 180 segundos, Espa\u00f1a hab\u00eda derribado a Francia.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\">La segunda parte no dio respiro. Cuando Deschamps buscaba soluciones, Espa\u00f1a aument\u00f3 la presi\u00f3n. Lamine Yamal, en un desborde que confirm\u00f3 su imparable madurez, forz\u00f3 un penalti que \u00e9l mismo convirti\u00f3 para el 3-0 en el 54\u2019. Un minuto m\u00e1s tarde, Pedri, que hab\u00eda comenzado el partido maniatado, firm\u00f3 el cuarto con una exquisita definici\u00f3n tras asistencia de Nico. Aunque Francia intent\u00f3 reaccionar en el tramo final, &#8216;La Roja&#8217; ya ten\u00eda el partido bajo control.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-6 wp-block-paragraph\">El triunfo no solo confirm\u00f3 el crecimiento de una generaci\u00f3n joven, con nombres como Lamine, Nico y Pedri brillando a gran altura, sino que tambi\u00e9n ratific\u00f3 el car\u00e1cter de un equipo que juega con la tranquilidad de los grandes. El pr\u00f3ximo domingo, Espa\u00f1a buscar\u00e1 en M\u00fanich su segundo t\u00edtulo consecutivo de la Nations League, esta vez frente a Portugal. La obra todav\u00eda no est\u00e1 terminada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Espa\u00f1a tumba a Francia y defender\u00e1 t\u00edtulo ante Portugal. &#8216;La Roja&#8217; dominaba por 5-1 en el 67\u2019. Francia pese a sus esfuerzos y encontrar el 5-4, termin\u00f3 sucumbiendo al l\u00edmite. Espa\u00f1a volvi\u00f3 a demostrar que, a veces, el verdadero arte en el f\u00fatbol es hacer simple lo extraordinario. Sin levantar la voz, con precisi\u00f3n quir\u00fargica [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[47,677,676,48,49,512,669,671,675],"class_list":["post-7716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-internacional","tag-antigua-esportiva","tag-espana","tag-francia","tag-kenny-rodas","tag-kenny-sports","tag-lamine-yamal","tag-nations-league","tag-portugal","tag-uefa-nations-league"],"_links":{"self":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts\/7716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/comments?post=7716"}],"version-history":[{"count":1,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts\/7716\/revisions"}],"predecessor-version":[{"id":7718,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts\/7716\/revisions\/7718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/media\/7717"}],"wp:attachment":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/media?parent=7716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/categories?post=7716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/tags?post=7716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}