{"id":7627,"date":"2025-05-31T18:26:32","date_gmt":"2025-06-01T00:26:32","guid":{"rendered":"https:\/\/antiguaesportiva.com\/revista\/?p=7627"},"modified":"2025-05-31T18:26:34","modified_gmt":"2025-06-01T00:26:34","slug":"el-psg-alza-la-champions-por-primera-vez-en-su-historia-luego-de-una-goleada-para-la-historia-ante-el-inter","status":"publish","type":"post","link":"https:\/\/antiguaesportiva.com\/revista\/2025\/05\/31\/el-psg-alza-la-champions-por-primera-vez-en-su-historia-luego-de-una-goleada-para-la-historia-ante-el-inter\/","title":{"rendered":"El PSG alza la Champions por primera vez en su historia, luego de una goleada para la historia ante el Inter"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">Hist\u00f3rico: El PSG arrasa al Inter y conquista su primera Champions League con una goleada sin precedentes<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">El Paris Saint-Germain hizo historia en M\u00fanich. No solo logr\u00f3 su primera Champions League, sino que lo hizo de forma apabullante, con una actuaci\u00f3n que quedar\u00e1 registrada como una de las m\u00e1s dominantes en la historia del torneo. Los dirigidos por Luis Enrique borraron del mapa al Inter de Mil\u00e1n en apenas 20 minutos y terminaron imponi\u00e9ndose 5-0 en una final completamente desequilibrada.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.formacionsecretarial.edu.gt\/\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"708\" src=\"https:\/\/antiguaesportiva.com\/revista\/wp-content\/uploads\/2025\/05\/nueva-ubica-manta-2@2x.png\" alt=\"\" class=\"wp-image-7483\" style=\"width:294px;height:auto\" srcset=\"https:\/\/antiguaesportiva.com\/revista\/wp-content\/uploads\/2025\/05\/nueva-ubica-manta-2@2x.png 500w, https:\/\/antiguaesportiva.com\/revista\/wp-content\/uploads\/2025\/05\/nueva-ubica-manta-2@2x-212x300.png 212w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">El camino hasta la gloria ya hab\u00eda sido exigente, tras superar a Brest, Liverpool, Aston Villa y Arsenal. Pero en el Allianz Arena, el PSG mostr\u00f3 su mejor versi\u00f3n. Liderados por un estelar D\u00e9sir\u00e9 Dou\u00e9 \u2014autor de dos goles y una asistencia\u2014, los parisinos sentenciaron el encuentro muy temprano. A los 11 minutos, Achraf Hakimi abri\u00f3 el marcador tras una jugada milim\u00e9trica. Minutos despu\u00e9s, Dou\u00e9 ampli\u00f3 la ventaja tras un contragolpe letal. El joven franc\u00e9s, que rozar\u00e1 los 20 a\u00f1os en unos d\u00edas, firm\u00f3 una de las mejores actuaciones individuales en una final europea.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\">La superioridad del PSG fue absoluta. Se convirtieron en el primer equipo en la historia en marcar dos goles en los primeros 20 minutos de una final de Champions League. Mientras tanto, el Inter apenas generaba peligro, con solo un par de ocasiones aisladas que no inquietaron seriamente a Donnarumma, quien tambi\u00e9n firm\u00f3 una actuaci\u00f3n destacada en el arco parisino.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\">El segundo tiempo fue un baile. Sin respuesta por parte de los italianos, el PSG continu\u00f3 atacando con autoridad. Dou\u00e9, en su noche consagratoria, anot\u00f3 el tercero tras otro contragolpe magistral, y Kvaratskhelia ampli\u00f3 la goleada al 4-0. Finalmente, Mayulu puso cifras definitivas con el quinto tanto, completando as\u00ed la mayor goleada en la historia de una final de Copa de Europa o Champions League.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-6 wp-block-paragraph\">Con este triunfo, el PSG alcanza por fin el sue\u00f1o que persigui\u00f3 durante m\u00e1s de una d\u00e9cada desde la llegada de Qatar en 2011. Adem\u00e1s de conquistar su primera Champions, el club parisino completa el ansiado Triplete (Ligue 1, Coupe de France y Champions League), el segundo en la carrera de Luis Enrique, y se posiciona como uno de los grandes favoritos para el pr\u00f3ximo Mundial de Clubes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hist\u00f3rico: El PSG arrasa al Inter y conquista su primera Champions League con una goleada sin precedentes El Paris Saint-Germain hizo historia en M\u00fanich. No solo logr\u00f3 su primera Champions League, sino que lo hizo de forma apabullante, con una actuaci\u00f3n que quedar\u00e1 registrada como una de las m\u00e1s dominantes en la historia del torneo. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7628,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[47,63,336,48,49,607,606,61],"class_list":["post-7627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-internacional","tag-antigua-esportiva","tag-champions","tag-champions-league","tag-kenny-rodas","tag-kenny-sports","tag-paris-sg","tag-psg","tag-ucl"],"_links":{"self":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts\/7627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/comments?post=7627"}],"version-history":[{"count":1,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts\/7627\/revisions"}],"predecessor-version":[{"id":7629,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts\/7627\/revisions\/7629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/media\/7628"}],"wp:attachment":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/media?parent=7627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/categories?post=7627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/tags?post=7627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}