{"id":13601,"date":"2026-05-23T16:53:15","date_gmt":"2026-05-23T22:53:15","guid":{"rendered":"https:\/\/antiguaesportiva.com\/revista\/?p=13601"},"modified":"2026-05-23T16:54:21","modified_gmt":"2026-05-23T22:54:21","slug":"mbappe-bi-campeon-del-trofeo-pichichi-de-la-liga","status":"publish","type":"post","link":"https:\/\/antiguaesportiva.com\/revista\/2026\/05\/23\/mbappe-bi-campeon-del-trofeo-pichichi-de-la-liga\/","title":{"rendered":"\u00a1Mbapp\u00e9, Bi-Campe\u00f3n del Trofeo Pichichi de la Liga!"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">Con un derechazo fulminante ante el Athletic Club, Kylian Mbapp\u00e9 alcanz\u00f3 los 25 goles y se proclam\u00f3 bicampe\u00f3n del Trofeo Pichichi de LaLiga.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">Kylian Mbapp\u00e9 ha asegurado de forma matem\u00e1tica el liderato de la tabla de goleadores de LaLiga EA Sports a falta de que se dispute el encuentro entre el Villarreal y el Atl\u00e9tico de Madrid. Con su anotaci\u00f3n de pierna derecha en el minuto 51 ante el Athletic Club, el delantero del Real Madrid alcanz\u00f3 los 25 tantos en la temporada, una cifra que lo consolida de manera definitiva como el m\u00e1ximo artillero del campeonato espa\u00f1ol y le otorga su segundo trofeo Pichichi consecutivo. A pesar de que el conjunto blanco no logr\u00f3 conquistar t\u00edtulos colectivos en este curso, el atacante franc\u00e9s revalida su impacto individual en el f\u00fatbol ib\u00e9rico tras los 31 goles firmados en su campa\u00f1a de debut.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">El principal perseguidor del madridista fue el kosovar Vedat Muriqi, quien cerr\u00f3 una notable participaci\u00f3n individual con 23 aciertos, incluyendo un gol en la \u00faltima jornada que result\u00f3 insuficiente para el Mallorca. El equipo balear no pudo evitar el descenso a LaLiga Hypermotion, firmando un doloroso desenlace colectivo que contrasta con el rendimiento de su referente en ataque. Por su parte, la tercera plaza de la clasificaci\u00f3n fue para el croata Ante Budimir, quien sum\u00f3 17 dianas con el Osasuna en una campa\u00f1a destinada a asegurar la permanencia, consolid\u00e1ndose como uno de los delanteros m\u00e1s fiables de la competici\u00f3n.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\">La tabla de goleadores tras 37 jornadas refleja la marcada regularidad de los l\u00edderes y la paridad en los puestos inmediatos. Detr\u00e1s del podio compuesto por Mbapp\u00e9 (25 goles, 8 de penalti), Muriqi (23 goles, 4 de penalti) y Budimir (17 goles, 5 de penalti), se ubicaron Lamine Yamal (Barcelona) y Vin\u00edcius J\u00fanior (Real Madrid) con 16 tantos cada uno, seguidos de cerca por Ferran Torres (Barcelona) y Mikel Oyarzabal (Real Sociedad), quienes finalizaron el campeonato con 15 anotaciones en sus cuentas personales.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\">Este nuevo galard\u00f3n individual eleva el palmar\u00e9s de Kylian Mbapp\u00e9 a un total de ocho t\u00edtulos de goleo en ligas de primera divisi\u00f3n, sumando los dos obtenidos en Espa\u00f1a a los seis que cosech\u00f3 en la Ligue 1 de Francia, donde se mantiene como el m\u00e1ximo anotador hist\u00f3rico. No obstante, en el contexto del f\u00fatbol espa\u00f1ol, el franc\u00e9s se sit\u00faa todav\u00eda a tres distinciones de igualar el registro hist\u00f3rico de Lionel Messi, quien permanece como el \u00fanico futbolista capaz de encadenar cinco trofeos Pichichi de manera consecutiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un derechazo fulminante ante el Athletic Club, Kylian Mbapp\u00e9 alcanz\u00f3 los 25 goles y se proclam\u00f3 bicampe\u00f3n del Trofeo Pichichi de LaLiga. Kylian Mbapp\u00e9 ha asegurado de forma matem\u00e1tica el liderato de la tabla de goleadores de LaLiga EA Sports a falta de que se dispute el encuentro entre el Villarreal y el Atl\u00e9tico [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":13602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[47,48,49,60,1808,58],"class_list":["post-13601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-internacional","tag-antigua-esportiva","tag-kenny-rodas","tag-kenny-sports","tag-mbappe","tag-pichichi","tag-real-madrid"],"_links":{"self":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts\/13601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/comments?post=13601"}],"version-history":[{"count":2,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts\/13601\/revisions"}],"predecessor-version":[{"id":13604,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/posts\/13601\/revisions\/13604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/media\/13602"}],"wp:attachment":[{"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/media?parent=13601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/categories?post=13601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antiguaesportiva.com\/revista\/wp-json\/wp\/v2\/tags?post=13601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}